{"id":8128,"date":"2023-12-13T11:48:51","date_gmt":"2023-12-13T11:48:51","guid":{"rendered":"http:\/\/coats.com\/?post_type=media-library&#038;p=8128"},"modified":"2024-01-08T12:08:19","modified_gmt":"2024-01-08T12:08:19","slug":"denim-visualiser","status":"publish","type":"media-library","link":"https:\/\/www.coats.com\/es\/media-library\/denim-visualiser\/","title":{"rendered":"Visualizador de Mezclilla"},"parent":0,"template":"","meta":{"_acf_changed":false},"media-categories":[153],"class_list":["post-8128","media-library","type-media-library","status-publish","hentry","media-categories-productservices"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.2 (Yoast SEO v25.2) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Denim Visualiser | Coats Group plc<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.coats.com\/es\/media-library\/denim-visualiser\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Denim Visualiser | Coats Group plc\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.coats.com\/es\/media-library\/denim-visualiser\/\" \/>\n<meta property=\"og:site_name\" content=\"Coats Group plc\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-08T12:08:19+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.coats.com\/es\/media-library\/denim-visualiser\/\",\"url\":\"https:\/\/www.coats.com\/es\/media-library\/denim-visualiser\/\",\"name\":\"Denim Visualiser | Coats Group plc\",\"isPartOf\":{\"@id\":\"https:\/\/www.coats.com\/es\/#website\"},\"datePublished\":\"2023-12-13T11:48:51+00:00\",\"dateModified\":\"2024-01-08T12:08:19+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.coats.com\/es\/media-library\/denim-visualiser\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.coats.com\/es\/#website\",\"url\":\"https:\/\/www.coats.com\/es\/\",\"name\":\"Coats Group plc\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.coats.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.coats.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.coats.com\/es\/#organization\",\"name\":\"Coats Group plc\",\"url\":\"https:\/\/www.coats.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.coats.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cdn.coats.com\/wp-content\/uploads\/coats-logo.svg\",\"contentUrl\":\"https:\/\/cdn.coats.com\/wp-content\/uploads\/coats-logo.svg\",\"width\":79,\"height\":79,\"caption\":\"Coats Group plc\"},\"image\":{\"@id\":\"https:\/\/www.coats.com\/es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Denim Visualiser | Coats Group plc","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.coats.com\/es\/media-library\/denim-visualiser\/","og_locale":"es_ES","og_type":"article","og_title":"Denim Visualiser | Coats Group plc","og_url":"https:\/\/www.coats.com\/es\/media-library\/denim-visualiser\/","og_site_name":"Coats Group plc","article_modified_time":"2024-01-08T12:08:19+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.coats.com\/es\/media-library\/denim-visualiser\/","url":"https:\/\/www.coats.com\/es\/media-library\/denim-visualiser\/","name":"Denim Visualiser | Coats Group plc","isPartOf":{"@id":"https:\/\/www.coats.com\/es\/#website"},"datePublished":"2023-12-13T11:48:51+00:00","dateModified":"2024-01-08T12:08:19+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.coats.com\/es\/media-library\/denim-visualiser\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.coats.com\/es\/#website","url":"https:\/\/www.coats.com\/es\/","name":"Coats Group plc","description":"","publisher":{"@id":"https:\/\/www.coats.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.coats.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.coats.com\/es\/#organization","name":"Coats Group plc","url":"https:\/\/www.coats.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.coats.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/cdn.coats.com\/wp-content\/uploads\/coats-logo.svg","contentUrl":"https:\/\/cdn.coats.com\/wp-content\/uploads\/coats-logo.svg","width":79,"height":79,"caption":"Coats Group plc"},"image":{"@id":"https:\/\/www.coats.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.coats.com\/es\/wp-json\/wp\/v2\/media-library\/8128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.coats.com\/es\/wp-json\/wp\/v2\/media-library"}],"about":[{"href":"https:\/\/www.coats.com\/es\/wp-json\/wp\/v2\/types\/media-library"}],"version-history":[{"count":0,"href":"https:\/\/www.coats.com\/es\/wp-json\/wp\/v2\/media-library\/8128\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.coats.com\/es\/wp-json\/wp\/v2\/media?parent=8128"}],"wp:term":[{"taxonomy":"media-categories","embeddable":true,"href":"https:\/\/www.coats.com\/es\/wp-json\/wp\/v2\/media-categories?post=8128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}