{"id":18222,"date":"2024-02-16T19:33:37","date_gmt":"2024-02-16T19:33:37","guid":{"rendered":"http:\/\/coats.com\/?post_type=global-directory&#038;p=18222"},"modified":"2026-07-29T14:24:04","modified_gmt":"2026-07-29T08:54:04","slug":"venezuela","status":"publish","type":"global-directory","link":"https:\/\/www.coats.com\/es\/global-directory\/venezuela\/","title":{"rendered":"Venezuela"},"content":{"rendered":"<p><strong>Coats Cadena Andina S.A.<\/strong><br>Avenida Santander,<br>#5E &#8211; 87 Kennedy Pereira,<br>660001 Risaralda. Colombia<br><br>E: <a href=\"mailto:alejandro.betancourt@coats.com?subject=Coats.com\/en\/%20-%20Venezuela%20-%20Enquiry\">alejandro.betancourt@coats.com<\/a><\/p>","protected":false},"parent":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"global-directory-category":[208],"class_list":["post-18222","global-directory","type-global-directory","status-publish","hentry","global-directory-category-americas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.2 (Yoast SEO v25.2) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Venezuela | Coats Group plc<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Venezuela | Coats Group plc\" \/>\n<meta property=\"og:description\" content=\"Coats Cadena Andina S.A.Avenida Santander,#5E &#8211; 87 Kennedy Pereira,660001 Risaralda. Colombia E: alejandro.betancourt@coats.com\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.coats.com\/es\/global-directory\/venezuela\/\" \/>\n<meta property=\"og:site_name\" content=\"Coats Group plc\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-29T08:54:04+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.coats.com\/es\/global-directory\/venezuela\/\",\"url\":\"https:\/\/www.coats.com\/es\/global-directory\/venezuela\/\",\"name\":\"Venezuela | Coats Group plc\",\"isPartOf\":{\"@id\":\"https:\/\/www.coats.com\/es\/#website\"},\"datePublished\":\"2024-02-16T19:33:37+00:00\",\"dateModified\":\"2026-07-29T08:54:04+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.coats.com\/es\/global-directory\/venezuela\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.coats.com\/es\/#website\",\"url\":\"https:\/\/www.coats.com\/es\/\",\"name\":\"Coats Group plc\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.coats.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.coats.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.coats.com\/es\/#organization\",\"name\":\"Coats Group plc\",\"url\":\"https:\/\/www.coats.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.coats.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cdn.coats.com\/wp-content\/uploads\/coats-logo.svg\",\"contentUrl\":\"https:\/\/cdn.coats.com\/wp-content\/uploads\/coats-logo.svg\",\"width\":79,\"height\":79,\"caption\":\"Coats Group plc\"},\"image\":{\"@id\":\"https:\/\/www.coats.com\/es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Venezuela | Coats Group plc","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"Venezuela | Coats Group plc","og_description":"Coats Cadena Andina S.A.Avenida Santander,#5E &#8211; 87 Kennedy Pereira,660001 Risaralda. Colombia E: alejandro.betancourt@coats.com","og_url":"https:\/\/www.coats.com\/es\/global-directory\/venezuela\/","og_site_name":"Coats Group plc","article_modified_time":"2026-07-29T08:54:04+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.coats.com\/es\/global-directory\/venezuela\/","url":"https:\/\/www.coats.com\/es\/global-directory\/venezuela\/","name":"Venezuela | Coats Group plc","isPartOf":{"@id":"https:\/\/www.coats.com\/es\/#website"},"datePublished":"2024-02-16T19:33:37+00:00","dateModified":"2026-07-29T08:54:04+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.coats.com\/es\/global-directory\/venezuela\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.coats.com\/es\/#website","url":"https:\/\/www.coats.com\/es\/","name":"Coats Group plc","description":"","publisher":{"@id":"https:\/\/www.coats.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.coats.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.coats.com\/es\/#organization","name":"Coats Group plc","url":"https:\/\/www.coats.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.coats.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/cdn.coats.com\/wp-content\/uploads\/coats-logo.svg","contentUrl":"https:\/\/cdn.coats.com\/wp-content\/uploads\/coats-logo.svg","width":79,"height":79,"caption":"Coats Group plc"},"image":{"@id":"https:\/\/www.coats.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.coats.com\/es\/wp-json\/wp\/v2\/global-directory\/18222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.coats.com\/es\/wp-json\/wp\/v2\/global-directory"}],"about":[{"href":"https:\/\/www.coats.com\/es\/wp-json\/wp\/v2\/types\/global-directory"}],"version-history":[{"count":4,"href":"https:\/\/www.coats.com\/es\/wp-json\/wp\/v2\/global-directory\/18222\/revisions"}],"predecessor-version":[{"id":42329,"href":"https:\/\/www.coats.com\/es\/wp-json\/wp\/v2\/global-directory\/18222\/revisions\/42329"}],"wp:attachment":[{"href":"https:\/\/www.coats.com\/es\/wp-json\/wp\/v2\/media?parent=18222"}],"wp:term":[{"taxonomy":"global-directory-category","embeddable":true,"href":"https:\/\/www.coats.com\/es\/wp-json\/wp\/v2\/global-directory-category?post=18222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}