{"id":8034,"date":"2023-12-30T06:11:56","date_gmt":"2023-12-30T06:11:56","guid":{"rendered":"http:\/\/coats.com\/?post_type=media-library&#038;p=8034"},"modified":"2024-01-08T08:12:24","modified_gmt":"2024-01-08T08:12:24","slug":"2023-sustainability-strategy-with-christopher-dearing","status":"publish","type":"media-library","link":"https:\/\/www.coats.com\/de\/media-library\/2023-sustainability-strategy-with-christopher-dearing\/","title":{"rendered":"2023 Sustainability Strategy with Christopher Dearing"},"parent":0,"template":"","meta":{"_acf_changed":false},"media-categories":[153],"class_list":["post-8034","media-library","type-media-library","status-publish","hentry","media-categories-productservices"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.2 (Yoast SEO v25.2) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>2023 Sustainability Strategy with Christopher Dearing | Coats Group plc<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.coats.com\/de\/media-library\/2023-sustainability-strategy-with-christopher-dearing\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2023 Sustainability Strategy with Christopher Dearing | Coats Group plc\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.coats.com\/de\/media-library\/2023-sustainability-strategy-with-christopher-dearing\/\" \/>\n<meta property=\"og:site_name\" content=\"Coats Group plc\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-08T08:12:24+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.coats.com\/de\/media-library\/2023-sustainability-strategy-with-christopher-dearing\/\",\"url\":\"https:\/\/www.coats.com\/de\/media-library\/2023-sustainability-strategy-with-christopher-dearing\/\",\"name\":\"2023 Sustainability Strategy with Christopher Dearing | Coats Group plc\",\"isPartOf\":{\"@id\":\"https:\/\/www.coats.com\/de\/#website\"},\"datePublished\":\"2023-12-30T06:11:56+00:00\",\"dateModified\":\"2024-01-08T08:12:24+00:00\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.coats.com\/de\/media-library\/2023-sustainability-strategy-with-christopher-dearing\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.coats.com\/de\/#website\",\"url\":\"https:\/\/www.coats.com\/de\/\",\"name\":\"Coats Group plc\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.coats.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.coats.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.coats.com\/de\/#organization\",\"name\":\"Coats Group plc\",\"url\":\"https:\/\/www.coats.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.coats.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cdn.coats.com\/wp-content\/uploads\/coats-logo.svg\",\"contentUrl\":\"https:\/\/cdn.coats.com\/wp-content\/uploads\/coats-logo.svg\",\"width\":79,\"height\":79,\"caption\":\"Coats Group plc\"},\"image\":{\"@id\":\"https:\/\/www.coats.com\/de\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"2023 Sustainability Strategy with Christopher Dearing | Coats Group plc","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.coats.com\/de\/media-library\/2023-sustainability-strategy-with-christopher-dearing\/","og_locale":"de_DE","og_type":"article","og_title":"2023 Sustainability Strategy with Christopher Dearing | Coats Group plc","og_url":"https:\/\/www.coats.com\/de\/media-library\/2023-sustainability-strategy-with-christopher-dearing\/","og_site_name":"Coats Group plc","article_modified_time":"2024-01-08T08:12:24+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.coats.com\/de\/media-library\/2023-sustainability-strategy-with-christopher-dearing\/","url":"https:\/\/www.coats.com\/de\/media-library\/2023-sustainability-strategy-with-christopher-dearing\/","name":"2023 Sustainability Strategy with Christopher Dearing | Coats Group plc","isPartOf":{"@id":"https:\/\/www.coats.com\/de\/#website"},"datePublished":"2023-12-30T06:11:56+00:00","dateModified":"2024-01-08T08:12:24+00:00","inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.coats.com\/de\/media-library\/2023-sustainability-strategy-with-christopher-dearing\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.coats.com\/de\/#website","url":"https:\/\/www.coats.com\/de\/","name":"Coats Group plc","description":"","publisher":{"@id":"https:\/\/www.coats.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.coats.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.coats.com\/de\/#organization","name":"Coats Group plc","url":"https:\/\/www.coats.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.coats.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/cdn.coats.com\/wp-content\/uploads\/coats-logo.svg","contentUrl":"https:\/\/cdn.coats.com\/wp-content\/uploads\/coats-logo.svg","width":79,"height":79,"caption":"Coats Group plc"},"image":{"@id":"https:\/\/www.coats.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.coats.com\/de\/wp-json\/wp\/v2\/media-library\/8034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.coats.com\/de\/wp-json\/wp\/v2\/media-library"}],"about":[{"href":"https:\/\/www.coats.com\/de\/wp-json\/wp\/v2\/types\/media-library"}],"version-history":[{"count":0,"href":"https:\/\/www.coats.com\/de\/wp-json\/wp\/v2\/media-library\/8034\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.coats.com\/de\/wp-json\/wp\/v2\/media?parent=8034"}],"wp:term":[{"taxonomy":"media-categories","embeddable":true,"href":"https:\/\/www.coats.com\/de\/wp-json\/wp\/v2\/media-categories?post=8034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}